{"id":99,"count":4,"description":"","link":"https:\/\/mobiledis.com\/en\/category\/iluminacion\/","name":"Iluminaci\u00f3n","slug":"iluminacion","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/categories\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/posts?categories=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}