{"id":20,"count":5,"description":"","link":"https:\/\/mobiledis.com\/en\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mobiledis.com\/en\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}